{"id":54,"count":5,"description":"","link":"https:\/\/diihk.com\/en\/category\/archived-events-en\/","name":"archived events","slug":"archived-events-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>archived events Archives - \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diihk.com\/en\/category\/archived-events-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"archived events Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diihk.com\/en\/category\/archived-events-en\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/diihk.com\/en\/category\/archived-events-en\/\",\"url\":\"https:\/\/diihk.com\/en\/category\/archived-events-en\/\",\"name\":\"archived events Archives - \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/diihk.com\/en\/category\/archived-events-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diihk.com\/en\/category\/archived-events-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/diihk.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"archived events\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diihk.com\/en\/#website\",\"url\":\"https:\/\/diihk.com\/en\/\",\"name\":\"German-Iranian Chamber of Industry and Commerce\",\"description\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"publisher\":{\"@id\":\"https:\/\/diihk.com\/en\/#organization\"},\"alternateName\":\"DIIHK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diihk.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diihk.com\/en\/#organization\",\"name\":\"\u0627\u062a\u0627\u0642 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646\",\"alternateName\":\"DIIHK\",\"url\":\"https:\/\/diihk.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/diihk.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"width\":215,\"height\":72,\"caption\":\"\u0627\u062a\u0627\u0642 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"archived events Archives - \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diihk.com\/en\/category\/archived-events-en\/","og_locale":"en_US","og_type":"article","og_title":"archived events Archives","og_url":"https:\/\/diihk.com\/en\/category\/archived-events-en\/","og_site_name":"\u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/diihk.com\/en\/category\/archived-events-en\/","url":"https:\/\/diihk.com\/en\/category\/archived-events-en\/","name":"archived events Archives - \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646","isPartOf":{"@id":"https:\/\/diihk.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/diihk.com\/en\/category\/archived-events-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/diihk.com\/en\/category\/archived-events-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diihk.com\/en\/"},{"@type":"ListItem","position":2,"name":"archived events"}]},{"@type":"WebSite","@id":"https:\/\/diihk.com\/en\/#website","url":"https:\/\/diihk.com\/en\/","name":"German-Iranian Chamber of Industry and Commerce","description":"Deutsch-Iranische Industrie- und Handelskammer","publisher":{"@id":"https:\/\/diihk.com\/en\/#organization"},"alternateName":"DIIHK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diihk.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/diihk.com\/en\/#organization","name":"\u0627\u062a\u0627\u0642 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646","alternateName":"DIIHK","url":"https:\/\/diihk.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/diihk.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","width":215,"height":72,"caption":"\u0627\u062a\u0627\u0642 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0622\u0644\u0645\u0627\u0646"},"image":{"@id":"https:\/\/diihk.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/diihk.com\/en\/wp-json\/wp\/v2\/categories\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diihk.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/diihk.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/diihk.com\/en\/wp-json\/wp\/v2\/posts?categories=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}