{"id":20960,"date":"2025-08-07T09:37:28","date_gmt":"2025-08-07T06:07:28","guid":{"rendered":"https:\/\/diihk.com\/news\/080720250935\/"},"modified":"2025-08-07T10:20:12","modified_gmt":"2025-08-07T06:50:12","slug":"080720250935","status":"publish","type":"post","link":"https:\/\/diihk.com\/de\/news\/080720250935\/","title":{"rendered":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20960\" class=\"elementor elementor-20960 elementor-20937\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-523d7edc e-flex e-con-boxed e-con e-parent\" data-id=\"523d7edc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f589892 elementor-widget elementor-widget-heading\" data-id=\"5f589892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4c8791 elementor-widget elementor-widget-text-editor\" data-id=\"3a4c8791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab35691 elementor-widget elementor-widget-text-editor\" data-id=\"ab35691\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die 15-prozentige Zollvereinbarung, die Ende Juli von Donald Trump und Ursula von der Leyen als Ma\u00dfnahme zur Verhinderung eines umfassenderen Handelskonflikts angek\u00fcndigt wurde, wurde von deutschen Wirtschaftsf\u00fchrern als kostspieliger Kompromiss bezeichnet, der Europas &#8211; und insbesondere Deutschlands &#8211; Wettbewerbsf\u00e4higkeit auf den globalen M\u00e4rkten schw\u00e4chen k\u00f6nnte.<\/p>\n<p>Markus Kerber, Vorstandsvorsitzender des deutschen Energieriesen RWE, hat die Wirksamkeit des Abkommens offen in Frage gestellt. Unter Bezugnahme auf die Energieverpflichtungen, die den USA im Rahmen des Abkommens auferlegt wurden, erkl\u00e4rte er: \u201eDie Vereinigten Staaten k\u00f6nnen diese zus\u00e4tzliche Energiemenge einfach nicht produzieren\u201c. Seine \u00c4u\u00dferungen haben die Zweifel an der Realit\u00e4tsn\u00e4he der Bestimmungen des Abkommens verst\u00e4rkt und die Besorgnis \u00fcber die wachsende Energieabh\u00e4ngigkeit Europas verst\u00e4rkt. Kerber f\u00fcgte hinzu, dass es nicht nur unpraktisch, sondern auch risikoreich sei, von einem erh\u00f6hten Angebot auszugehen, wenn die Energieproduktion der USA bereits begrenzt sei.&nbsp;<\/p>\n<p><\/p>\n<p>Nach einer Umfrage des Deutschen Industrie- und Handelskammertages (DIHK) glauben fast 60 % der deutschen Unternehmen, dass das Abkommen den Handel nicht erleichtern, sondern vielmehr zus\u00e4tzlichen wirtschaftlichen Druck aus\u00fcben wird. Bei den Unternehmen mit direkten Verbindungen zum US-Markt sind es sogar 74 %. Viele dieser Unternehmen bef\u00fcrchten, dass die neuen Z\u00f6lle die Exportkosten erh\u00f6hen und ihre Position gegen\u00fcber amerikanischen und asiatischen Wettbewerbern schw\u00e4chen werden. Analysten warnen, dass die Folgen des Abkommens auf die deutsche Wirtschaft \u00fcbergreifen und sich auf Produktion, Besch\u00e4ftigung und Investitionen auswirken k\u00f6nnten.<\/p>\n<p>Lars Klingbeil, der deutsche Finanzminister und Vizekanzler, r\u00e4umte zwar ein, dass eine Einigung mit den USA notwendig sei, warnte aber, dass die Folgen das deutsche Wirtschaftswachstum stark beeintr\u00e4chtigen k\u00f6nnten. \u201eWir mussten eine Einigung erzielen, um Handelsspannungen zu vermeiden\u201c, sagte er, \u201eaber das Ergebnis dieses Kompromisses ist nichts anderes als eine Verlangsamung der deutschen Wirtschaft.\u201c Seine \u00c4u\u00dferungen spiegeln die wachsende Uneinigkeit innerhalb der europ\u00e4ischen Regierungen \u00fcber die Qualit\u00e4t und den Nutzen des Abkommens wider.<\/p>\n<p>Die Europ\u00e4ische Kommission reagierte auf die Kritik Klingbeils mit Verwunderung und betonte, dass Deutschland \u00fcber alle Verhandlungen und Entscheidungen umfassend informiert sei. Olof Gill, der handelspolitische Sprecher der Kommission, erkl\u00e4rte: \u201eKeine Entscheidung wurde ohne das Wissen und die Beteiligung der Mitgliedstaaten getroffen &#8211; insbesondere nicht von Deutschland, das w\u00e4hrend des gesamten Prozesses auf dem Laufenden gehalten wurde.\u201c Die Reaktion Br\u00fcssels l\u00e4sst vermuten, dass die Kritik Deutschlands eher auf innenpolitische Differenzen als auf den Inhalt des Abkommens selbst zur\u00fcckzuf\u00fchren ist.<\/p>\n<p>In der Zwischenzeit argumentieren einige Mitglieder des Europ\u00e4ischen Parlaments, wie Sonja Hahn von der deutschen FDP, dass das Abkommen keine klaren Vorteile f\u00fcr die EU biete und die Prinzipien des regelbasierten Handels untergrabe. Kritiker behaupten, dass die EU Zugest\u00e4ndnisse gemacht hat, ohne greifbare Vorteile zu erzielen, und warnen davor, dass dies einen Pr\u00e4zedenzfall f\u00fcr weitere einseitige Kompromisse in der Zukunft schaffen k\u00f6nnte.<\/p>\n<p>Obwohl die Vergeltungsz\u00f6lle der EU gegen die USA vor\u00fcbergehend ausgesetzt wurden, laufen die Verhandlungen weiter, und viele wichtige Fragen sind noch ungel\u00f6st. Die EU hat angek\u00fcndigt, dass ihre geplanten Z\u00f6lle auf amerikanische Waren im Wert von 93 Mrd. EUR um sechs Monate verschoben wurden, um Raum f\u00fcr eine tragf\u00e4higere Vereinbarung zu schaffen. Gleichzeitig betonte der deutsche Bundeskanzler Friedrich Merz, dass die EU eine konkrete Vereinbarung \u00fcber Stahlexportquoten anstrebt, um hohe Z\u00f6lle zu vermeiden. Er r\u00e4umte ein, dass das derzeitige Abkommen ein \u201eschwieriger Kompromiss\u201c sei, warnte aber davor, dass eine Eskalation der Handelsspannungen Europa schaden w\u00fcrde. Der n\u00e4chste Schritt sei die Festlegung pr\u00e4ziser und flexibler Bedingungen in sensiblen Sektoren wie der Stahlindustrie und verwandten Branchen.<\/p>\n<p>Quellen: Handelsblatt, Reuters, FT, DW<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.<\/p>\n","protected":false},"author":4,"featured_media":20940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-20960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA - Deutsch-Iranische Industrie- und Handelskammer<\/title>\n<meta name=\"description\" content=\"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diihk.com\/de\/news\/080720250935\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA\" \/>\n<meta property=\"og:description\" content=\"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diihk.com\/de\/news\/080720250935\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsch-Iranische Industrie- und Handelskammer\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T06:07:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T06:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Masoud Etesami\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Masoud Etesami\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/\"},\"author\":{\"name\":\"Masoud Etesami\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\"},\"headline\":\"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA\",\"datePublished\":\"2025-08-07T06:07:28+00:00\",\"dateModified\":\"2025-08-07T06:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/\"},\"wordCount\":669,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/diihk.com\/de\/news\/080720250935\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/\",\"url\":\"https:\/\/diihk.com\/de\/news\/080720250935\/\",\"name\":\"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA - Deutsch-Iranische Industrie- und Handelskammer\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg\",\"datePublished\":\"2025-08-07T06:07:28+00:00\",\"dateModified\":\"2025-08-07T06:50:12+00:00\",\"description\":\"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.\",\"breadcrumb\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diihk.com\/de\/news\/080720250935\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diihk.com\/de\/news\/080720250935\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/diihk.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/diihk.com\/de\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diihk.com\/de\/#website\",\"url\":\"https:\/\/diihk.com\/de\/\",\"name\":\"German-Iranian Chamber of Industry and Commerce\",\"description\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"alternateName\":\"DIIHK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diihk.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diihk.com\/de\/#organization\",\"name\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"alternateName\":\"DIIHK\",\"url\":\"https:\/\/diihk.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"width\":215,\"height\":72,\"caption\":\"Deutsch-Iranische Industrie- und Handelskammer\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\",\"name\":\"Masoud Etesami\",\"url\":\"https:\/\/diihk.com\/de\/author\/m_etesami\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA - Deutsch-Iranische Industrie- und Handelskammer","description":"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diihk.com\/de\/news\/080720250935\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA","og_description":"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.","og_url":"https:\/\/diihk.com\/de\/news\/080720250935\/","og_site_name":"Deutsch-Iranische Industrie- und Handelskammer","article_published_time":"2025-08-07T06:07:28+00:00","article_modified_time":"2025-08-07T06:50:12+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg","type":"image\/jpeg"}],"author":"Masoud Etesami","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Masoud Etesami","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#article","isPartOf":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/"},"author":{"name":"Masoud Etesami","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22"},"headline":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA","datePublished":"2025-08-07T06:07:28+00:00","dateModified":"2025-08-07T06:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/"},"wordCount":669,"commentCount":0,"publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diihk.com\/de\/news\/080720250935\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diihk.com\/de\/news\/080720250935\/","url":"https:\/\/diihk.com\/de\/news\/080720250935\/","name":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA - Deutsch-Iranische Industrie- und Handelskammer","isPartOf":{"@id":"https:\/\/diihk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg","datePublished":"2025-08-07T06:07:28+00:00","dateModified":"2025-08-07T06:50:12+00:00","description":"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.","breadcrumb":{"@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diihk.com\/de\/news\/080720250935\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#primaryimage","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/diihk.com\/de\/news\/080720250935\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diihk.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/diihk.com\/de\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Deutsche Unzufriedenheit \u00fcber das 15 %-Zollabkommen zwischen der EU und den USA"}]},{"@type":"WebSite","@id":"https:\/\/diihk.com\/de\/#website","url":"https:\/\/diihk.com\/de\/","name":"German-Iranian Chamber of Industry and Commerce","description":"Deutsch-Iranische Industrie- und Handelskammer","publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"alternateName":"DIIHK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diihk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/diihk.com\/de\/#organization","name":"Deutsch-Iranische Industrie- und Handelskammer","alternateName":"DIIHK","url":"https:\/\/diihk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","width":215,"height":72,"caption":"Deutsch-Iranische Industrie- und Handelskammer"},"image":{"@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22","name":"Masoud Etesami","url":"https:\/\/diihk.com\/de\/author\/m_etesami\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg",1500,1000,false],"landscape":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg",1500,1000,false],"portraits":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg",1500,1000,false],"thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-300x200.jpeg",300,200,true],"medium":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-500x333.jpeg",500,333,true],"large":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1200x800.jpeg",1200,800,true],"1536x1536":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg",1500,1000,false],"2048x2048":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei.jpeg",1500,1000,false],"be_thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-150x150.jpeg",150,150,true],"be_clients":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-113x75.jpeg",113,75,true],"slider-content":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1500x860.jpeg",1500,860,true],"portfolio-mf":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1280x1000.jpeg",1280,1000,true],"portfolio-mf-w":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1280x500.jpeg",1280,500,true],"portfolio-mf-t":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-768x1000.jpeg",768,1000,true],"portfolio-list":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1500x750.jpeg",1500,750,true],"blog-portfolio":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-960x720.jpeg",960,720,true],"blog-single":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-1200x675.jpeg",1200,675,true],"mobile-srcset":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/08\/archiv-01042025-niedersachsen-emden-autos-aus-dem-volkswagen-konzern-werden-zum-export-auf-ei-480x320.jpeg",480,320,true]},"rttpg_author":{"display_name":"Masoud Etesami","author_link":"https:\/\/diihk.com\/de\/author\/m_etesami\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diihk.com\/de\/category\/news\/\" rel=\"category tag\">News<\/a>","rttpg_excerpt":"Das j\u00fcngste Abkommen zwischen der Europ\u00e4ischen Union und den Vereinigten Staaten, das viele europ\u00e4ische Industrieg\u00fcter im Handel mit den USA mit einem 15 %-Zoll belegt, hat eine Welle der Kritik unter deutschen Regierungsvertretern und Wirtschaftsf\u00fchrern ausgel\u00f6st.","_links":{"self":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/comments?post=20960"}],"version-history":[{"count":10,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20960\/revisions"}],"predecessor-version":[{"id":20970,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20960\/revisions\/20970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media\/20940"}],"wp:attachment":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media?parent=20960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/categories?post=20960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/tags?post=20960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}