{"id":20598,"date":"2025-07-08T14:41:25","date_gmt":"2025-07-08T11:11:25","guid":{"rendered":"https:\/\/diihk.com\/news\/070820250237\/"},"modified":"2025-07-08T15:11:52","modified_gmt":"2025-07-08T11:41:52","slug":"070820250237","status":"publish","type":"post","link":"https:\/\/diihk.com\/de\/news\/070820250237\/","title":{"rendered":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20598\" class=\"elementor elementor-20598 elementor-20581\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-339241c2 e-flex e-con-boxed e-con e-parent\" data-id=\"339241c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3423a490 elementor-widget elementor-widget-heading\" data-id=\"3423a490\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b301ddd elementor-widget elementor-widget-text-editor\" data-id=\"7b301ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64a0f54b elementor-widget elementor-widget-text-editor\" data-id=\"64a0f54b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Laut Daten von Eurostat belief sich das gesamte Handelsvolumen zwischen dem Iran und der EU-27 von Januar bis April 2025 auf 1,31 Milliarden Euro. Dies entspricht einem R\u00fcckgang von 18 % gegen\u00fcber dem gleichen Zeitraum im Jahr 2024. Die Exporte der EU-27 in den Iran beliefen sich auf insgesamt 1,03 Milliarden Euro (-21 %), w\u00e4hrend die iranischen Exporte in die EU-27 bei etwa 280 Millionen Euro (-4 %) lagen. <\/p><p>Im April 2025 erreichte der bilaterale Handel 279 Millionen Euro und lag damit 16 % unter dem Wert von 330 Millionen Euro im April 2024. Die EU-Exporte in den Iran beliefen sich in diesem Monat auf 211 Millionen Euro (-17 %), w\u00e4hrend die iranischen Exporte in die EU mit 68 Millionen Euro (-10 %) angegeben wurden. <\/p><p>Basierend auf der Standard International Trade Classification (SITC) waren Chemikalien und verwandte Produkte, n. e. S. (SITC-Abschnitt 5) mit insgesamt 323 Millionen Euro die f\u00fchrende Kategorie der EU-Exporte in den Iran. Dies entspricht einem R\u00fcckgang von 4 % gegen\u00fcber dem Vorjahr. Auf iranischer Seite blieben Nahrungsmittel und Lebendtiere (SITC-Abschnitt 0) mit einem Wert von 126 Millionen Euro (+10 %) die wichtigste Exportgruppe in die EU. <\/p><p>Mit einem Handelsvolumen von insgesamt 426 Millionen Euro bleibt Deutschland der gr\u00f6\u00dfte Handelspartner des Iran in der EU, gefolgt von den Niederlanden (203 Millionen Euro), Italien (197 Millionen Euro) und Belgien (86 Millionen Euro).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5a8855 e-flex e-con-boxed e-con e-parent\" data-id=\"f5a8855\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e6f9b8 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9e6f9b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/Ausenhandel-EU-IR-Jan-bis-April-2025.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ausf\u00fchrliche Informationen zum Handel zwischen Iran und EU-27 | Januar bis April 2025<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.<\/p>\n","protected":false},"author":4,"featured_media":20584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-20598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025<\/title>\n<meta name=\"description\" content=\"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diihk.com\/de\/news\/070820250237\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025\" \/>\n<meta property=\"og:description\" content=\"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diihk.com\/de\/news\/070820250237\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsch-Iranische Industrie- und Handelskammer\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-08T11:11:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T11:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Masoud Etesami\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Masoud Etesami\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/\"},\"author\":{\"name\":\"Masoud Etesami\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\"},\"headline\":\"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025\",\"datePublished\":\"2025-07-08T11:11:25+00:00\",\"dateModified\":\"2025-07-08T11:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/diihk.com\/de\/news\/070820250237\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/\",\"url\":\"https:\/\/diihk.com\/de\/news\/070820250237\/\",\"name\":\"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg\",\"datePublished\":\"2025-07-08T11:11:25+00:00\",\"dateModified\":\"2025-07-08T11:41:52+00:00\",\"description\":\"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.\",\"breadcrumb\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diihk.com\/de\/news\/070820250237\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diihk.com\/de\/news\/070820250237\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/diihk.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/diihk.com\/de\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diihk.com\/de\/#website\",\"url\":\"https:\/\/diihk.com\/de\/\",\"name\":\"German-Iranian Chamber of Industry and Commerce\",\"description\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"alternateName\":\"DIIHK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diihk.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diihk.com\/de\/#organization\",\"name\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"alternateName\":\"DIIHK\",\"url\":\"https:\/\/diihk.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"width\":215,\"height\":72,\"caption\":\"Deutsch-Iranische Industrie- und Handelskammer\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\",\"name\":\"Masoud Etesami\",\"url\":\"https:\/\/diihk.com\/de\/author\/m_etesami\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025","description":"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diihk.com\/de\/news\/070820250237\/","og_locale":"de_DE","og_type":"article","og_title":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025","og_description":"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.","og_url":"https:\/\/diihk.com\/de\/news\/070820250237\/","og_site_name":"Deutsch-Iranische Industrie- und Handelskammer","article_published_time":"2025-07-08T11:11:25+00:00","article_modified_time":"2025-07-08T11:41:52+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg","type":"image\/jpeg"}],"author":"Masoud Etesami","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Masoud Etesami","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#article","isPartOf":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/"},"author":{"name":"Masoud Etesami","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22"},"headline":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025","datePublished":"2025-07-08T11:11:25+00:00","dateModified":"2025-07-08T11:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diihk.com\/de\/news\/070820250237\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diihk.com\/de\/news\/070820250237\/","url":"https:\/\/diihk.com\/de\/news\/070820250237\/","name":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025","isPartOf":{"@id":"https:\/\/diihk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg","datePublished":"2025-07-08T11:11:25+00:00","dateModified":"2025-07-08T11:41:52+00:00","description":"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.","breadcrumb":{"@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diihk.com\/de\/news\/070820250237\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#primaryimage","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/diihk.com\/de\/news\/070820250237\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diihk.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/diihk.com\/de\/category\/news\/"},{"@type":"ListItem","position":3,"name":"10 % Anstieg der iranischen Lebensmittelexporte in die EU Anfang 2025"}]},{"@type":"WebSite","@id":"https:\/\/diihk.com\/de\/#website","url":"https:\/\/diihk.com\/de\/","name":"German-Iranian Chamber of Industry and Commerce","description":"Deutsch-Iranische Industrie- und Handelskammer","publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"alternateName":"DIIHK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diihk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/diihk.com\/de\/#organization","name":"Deutsch-Iranische Industrie- und Handelskammer","alternateName":"DIIHK","url":"https:\/\/diihk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","width":215,"height":72,"caption":"Deutsch-Iranische Industrie- und Handelskammer"},"image":{"@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22","name":"Masoud Etesami","url":"https:\/\/diihk.com\/de\/author\/m_etesami\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg",1500,1000,false],"landscape":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg",1500,1000,false],"portraits":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg",1500,1000,false],"thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-300x200.jpg",300,200,true],"medium":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-500x333.jpg",500,333,true],"large":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1200x800.jpg",1200,800,true],"1536x1536":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg",1500,1000,false],"2048x2048":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420.jpg",1500,1000,false],"be_thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-150x150.jpg",150,150,true],"be_clients":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-113x75.jpg",113,75,true],"slider-content":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1500x860.jpg",1500,860,true],"portfolio-mf":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1280x1000.jpg",1280,1000,true],"portfolio-mf-w":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1280x500.jpg",1280,500,true],"portfolio-mf-t":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-768x1000.jpg",768,1000,true],"portfolio-list":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1500x750.jpg",1500,750,true],"blog-portfolio":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-960x720.jpg",960,720,true],"blog-single":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-1200x675.jpg",1200,675,true],"mobile-srcset":["https:\/\/diihk.com\/wp-content\/uploads\/2025\/07\/420-480x320.jpg",480,320,true]},"rttpg_author":{"display_name":"Masoud Etesami","author_link":"https:\/\/diihk.com\/de\/author\/m_etesami\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diihk.com\/de\/category\/news\/\" rel=\"category tag\">News<\/a>","rttpg_excerpt":"Der Iran exportierte in den ersten vier Monaten des Jahres 2025 Lebensmittel und Lebendtiere im Wert von 126 Millionen Euro in die EU-27, was einem Anstieg von 10 % gegen\u00fcber dem Vorjahr entspricht.","_links":{"self":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/comments?post=20598"}],"version-history":[{"count":4,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20598\/revisions"}],"predecessor-version":[{"id":20602,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/20598\/revisions\/20602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media\/20584"}],"wp:attachment":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media?parent=20598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/categories?post=20598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/tags?post=20598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}