{"id":11914,"date":"2024-04-21T11:57:14","date_gmt":"2024-04-21T08:27:14","guid":{"rendered":"https:\/\/diihk.com\/news\/042120241216\/"},"modified":"2024-05-19T15:25:28","modified_gmt":"2024-05-19T11:55:28","slug":"042120241216","status":"publish","type":"post","link":"https:\/\/diihk.com\/de\/news\/042120241216\/","title":{"rendered":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11914\" class=\"elementor elementor-11914 elementor-11894\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30cc6d43 e-flex e-con-boxed e-con e-parent\" data-id=\"30cc6d43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13721d25 elementor-widget elementor-widget-heading\" data-id=\"13721d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><b>Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4114e40 elementor-widget elementor-widget-text-editor\" data-id=\"4114e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd1dd2f elementor-widget elementor-widget-text-editor\" data-id=\"3fd1dd2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Von Januar bis Februar 2024 belief sich das Handelsvolumen zwischen Iran und Deutschland auf 282 Millionen Euro, was ein Anstieg von 15 % gegen\u00fcber dem gleichen Zeitraum des Vorjahres ist, als das Handelsvolumen 245 Millionen Euro betrug. In diesem Zeitraum exportierte Deutschland Waren im Wert von 241 Millionen Euro nach Iran; ein Anstieg von 22 % im Vergleich zum Vorjahr (197 Millionen Euro). In den ersten beiden Monaten des Jahres 2024 gingen \u00a0die iranischen Ausfuhren nach Deutschland\u00a0 auf 41 Mio. Euro zur\u00fcck, das sind 13 % weniger als im Vorjahreszeitraum (47 Mio. Euro).<\/p>\n<p>Im Monat Februar 2024 erreichte das Handelsvolumen zwischen Iran und Deutschland \u00a0einen Wert von 161 Millionen Euro, das sind 38% mehr als im Februar 2023 (116 Millionen Euro). Von diesem Betrag entfielen 141 Millionen Euro auf die deutschen Exporte nach Iran (+46 Prozent) und 20 Millionen Euro auf die iranischen Exporte nach Deutschland (+3 Prozent).<\/p>\n<p>Maschinenbauerzeugnisse (+44 %) sind die am h\u00e4ufigsten aus Deutschland in den Iran exportierten Waren, und Nahrungsmittel (+23 %) sind die gr\u00f6\u00dfte Gruppe von Waren, die der Iran nach Deutschland exportiert.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e6bf3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e8e6bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/Ausenhandel-DE-IR-Jan-bis-Februar-2024.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vollst\u00e4ndige Angaben zum Handel zwischen Iran und Deutschland - Januar bis Februar 2024<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.<\/p>\n","protected":false},"author":4,"featured_media":11900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-11914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.4 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent - Deutsch-Iranische Industrie- und Handelskammer<\/title>\n<meta name=\"description\" content=\"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diihk.com\/de\/news\/042120241216\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent\" \/>\n<meta property=\"og:description\" content=\"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diihk.com\/de\/news\/042120241216\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutsch-Iranische Industrie- und Handelskammer\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-21T08:27:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-19T11:55:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Masoud Etesami\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Masoud Etesami\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/\"},\"author\":{\"name\":\"Masoud Etesami\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\"},\"headline\":\"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent\",\"datePublished\":\"2024-04-21T08:27:14+00:00\",\"dateModified\":\"2024-05-19T11:55:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/diihk.com\/de\/news\/042120241216\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/\",\"url\":\"https:\/\/diihk.com\/de\/news\/042120241216\/\",\"name\":\"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent - Deutsch-Iranische Industrie- und Handelskammer\",\"isPartOf\":{\"@id\":\"https:\/\/diihk.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg\",\"datePublished\":\"2024-04-21T08:27:14+00:00\",\"dateModified\":\"2024-05-19T11:55:28+00:00\",\"description\":\"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.\",\"breadcrumb\":{\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diihk.com\/de\/news\/042120241216\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg\",\"width\":1000,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diihk.com\/de\/news\/042120241216\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/diihk.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/diihk.com\/de\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diihk.com\/de\/#website\",\"url\":\"https:\/\/diihk.com\/de\/\",\"name\":\"German-Iranian Chamber of Industry and Commerce\",\"description\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"publisher\":{\"@id\":\"https:\/\/diihk.com\/de\/#organization\"},\"alternateName\":\"DIIHK\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diihk.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/diihk.com\/de\/#organization\",\"name\":\"Deutsch-Iranische Industrie- und Handelskammer\",\"alternateName\":\"DIIHK\",\"url\":\"https:\/\/diihk.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"contentUrl\":\"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg\",\"width\":215,\"height\":72,\"caption\":\"Deutsch-Iranische Industrie- und Handelskammer\"},\"image\":{\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22\",\"name\":\"Masoud Etesami\",\"url\":\"https:\/\/diihk.com\/de\/author\/m_etesami\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent - Deutsch-Iranische Industrie- und Handelskammer","description":"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diihk.com\/de\/news\/042120241216\/","og_locale":"de_DE","og_type":"article","og_title":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent","og_description":"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.","og_url":"https:\/\/diihk.com\/de\/news\/042120241216\/","og_site_name":"Deutsch-Iranische Industrie- und Handelskammer","article_published_time":"2024-04-21T08:27:14+00:00","article_modified_time":"2024-05-19T11:55:28+00:00","og_image":[{"width":1000,"height":560,"url":"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg","type":"image\/jpeg"}],"author":"Masoud Etesami","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Masoud Etesami","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#article","isPartOf":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/"},"author":{"name":"Masoud Etesami","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22"},"headline":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent","datePublished":"2024-04-21T08:27:14+00:00","dateModified":"2024-05-19T11:55:28+00:00","mainEntityOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diihk.com\/de\/news\/042120241216\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diihk.com\/de\/news\/042120241216\/","url":"https:\/\/diihk.com\/de\/news\/042120241216\/","name":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent - Deutsch-Iranische Industrie- und Handelskammer","isPartOf":{"@id":"https:\/\/diihk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage"},"image":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage"},"thumbnailUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg","datePublished":"2024-04-21T08:27:14+00:00","dateModified":"2024-05-19T11:55:28+00:00","description":"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.","breadcrumb":{"@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diihk.com\/de\/news\/042120241216\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#primaryimage","url":"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg","width":1000,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/diihk.com\/de\/news\/042120241216\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diihk.com\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/diihk.com\/de\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Steigerung des Handelsvolumens zwischen Iran und Deutschland um 15 Prozent"}]},{"@type":"WebSite","@id":"https:\/\/diihk.com\/de\/#website","url":"https:\/\/diihk.com\/de\/","name":"German-Iranian Chamber of Industry and Commerce","description":"Deutsch-Iranische Industrie- und Handelskammer","publisher":{"@id":"https:\/\/diihk.com\/de\/#organization"},"alternateName":"DIIHK","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diihk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/diihk.com\/de\/#organization","name":"Deutsch-Iranische Industrie- und Handelskammer","alternateName":"DIIHK","url":"https:\/\/diihk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","contentUrl":"https:\/\/diihk.com\/wp-content\/uploads\/2025\/01\/DIIHK-main-logo-50-anniversary-LOW.svg","width":215,"height":72,"caption":"Deutsch-Iranische Industrie- und Handelskammer"},"image":{"@id":"https:\/\/diihk.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diihk.com\/de\/#\/schema\/person\/f3ac82846cd856138812963837db5f22","name":"Masoud Etesami","url":"https:\/\/diihk.com\/de\/author\/m_etesami\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"landscape":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"portraits":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-300x168.jpg",300,168,true],"medium":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-500x280.jpg",500,280,true],"large":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"1536x1536":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"2048x2048":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"be_thumbnail":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-150x150.jpg",150,150,true],"be_clients":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-134x75.jpg",134,75,true],"slider-content":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"portfolio-mf":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"portfolio-mf-w":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-1000x500.jpg",1000,500,true],"portfolio-mf-t":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-768x560.jpg",768,560,true],"portfolio-list":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"blog-portfolio":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-960x560.jpg",960,560,true],"blog-single":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715.jpg",1000,560,false],"mobile-srcset":["https:\/\/diihk.com\/wp-content\/uploads\/2024\/04\/715-480x269.jpg",480,269,true]},"rttpg_author":{"display_name":"Masoud Etesami","author_link":"https:\/\/diihk.com\/de\/author\/m_etesami\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diihk.com\/de\/category\/news\/\" rel=\"category tag\">News<\/a>","rttpg_excerpt":"Obwohl der Trend der iranischen Exporte nach Deutschland immer noch negativ ist, hat der Anstieg der deutschen Exporte in den Iran um 46% im Februar 2024 dazu gef\u00fchrt, dass das Handelsvolumen zwischen den beiden L\u00e4ndern in den ersten beiden Monaten des Jahres 2024 im Vergleich zum Vorjahreszeitraum um 15% gestiegen ist.","_links":{"self":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/11914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/comments?post=11914"}],"version-history":[{"count":7,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/11914\/revisions"}],"predecessor-version":[{"id":12540,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/posts\/11914\/revisions\/12540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media\/11900"}],"wp:attachment":[{"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/media?parent=11914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/categories?post=11914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diihk.com\/de\/wp-json\/wp\/v2\/tags?post=11914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}